{"id":6937,"date":"2025-07-03T21:19:06","date_gmt":"2025-07-03T18:19:06","guid":{"rendered":"https:\/\/startbigger.com\/home\/?page_id=6937"},"modified":"2026-03-24T10:19:25","modified_gmt":"2026-03-24T07:19:25","slug":"booking","status":"publish","type":"page","link":"https:\/\/startbigger.com\/home\/home-page\/booking\/","title":{"rendered":"\u062d\u062c\u0632 \u0627\u0633\u062a\u0634\u0627\u0631\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6937\" class=\"elementor elementor-6937\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ca60d3 e-flex e-con-boxed e-con e-parent\" data-id=\"3ca60d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaeda7d elementor-widget elementor-widget-heading\" data-id=\"eaeda7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u062e\u062a\u0631 \u0627\u0644\u064a\u0648\u0645  \u062b\u0645 \u0627\u0644\u0633\u0627\u0639\u0629 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0643 \u0644\u062d\u062c\u0632 \u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0645\u0639 \u062e\u0628\u0631\u0627\u0626\u0646\u0627\n<br>*\u064a\u0631\u062c\u0649 \u0627\u0636\u0627\u0641\u0629 \u0631\u0642\u0645 \u0647\u0627\u062a\u0641 \u064a\u0645\u062a\u0644\u0643 \u0627\u0644\u0648\u0627\u062a\u0633 \u0627\u0628 *<br>\n\u062d\u062a\u0649 \u062a\u0635\u0644\u0643 \u0631\u0633\u0627\u0644\u0629 \u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0645\u0648\u0639\u062f<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec62f3b elementor-widget elementor-widget-html\" data-id=\"ec62f3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/link.cashprocess.io\/widget\/booking\/cpzXcREScPj9GhNgNTeR\" style=\"width: 100%;border:none;overflow: hidden;\" scrolling=\"no\" id=\"cpzXcREScPj9GhNgNTeR_1756823404849\"><\/iframe><br><script src=\"https:\/\/link.cashprocess.io\/js\/form_embed.js\" type=\"text\/javascript\"><\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd3c088 elementor-widget elementor-widget-image\" data-id=\"fd3c088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/startbigger.com\/home\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"219\" src=\"https:\/\/startbigger.com\/home\/wp-content\/uploads\/2025\/03\/logo-dark-1024x280.png\" class=\"attachment-large size-large wp-image-5861\" alt=\"\" srcset=\"https:\/\/startbigger.com\/home\/wp-content\/uploads\/2025\/03\/logo-dark-1024x280.png 1024w, https:\/\/startbigger.com\/home\/wp-content\/uploads\/2025\/03\/logo-dark-300x82.png 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4a6ae51d e-flex e-con-boxed e-con e-parent\" data-id=\"4a6ae51d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ade6ada e-con-full e-flex e-con e-child\" data-id=\"7ade6ada\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a1e5477 elementor-widget elementor-widget-heading\" data-id=\"6a1e5477\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0627\u0644\u062e\u0637\u0648\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0628\u062f\u0627\u064a\u0629 \u0643\u0628\u064a\u0631\u0629 <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11e2f6f1 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"11e2f6f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/startbigger.com\/home\">\n\t\t\t<img decoding=\"async\" width=\"2121\" height=\"579\" src=\"https:\/\/startbigger.com\/home\/wp-content\/uploads\/2025\/03\/logo-light.png\" class=\"attachment-full size-full wp-image-5862\" alt=\"\" srcset=\"https:\/\/startbigger.com\/home\/wp-content\/uploads\/2025\/03\/logo-light.png 2121w, https:\/\/startbigger.com\/home\/wp-content\/uploads\/2025\/03\/logo-light-300x82.png 300w, https:\/\/startbigger.com\/home\/wp-content\/uploads\/2025\/03\/logo-light-1024x280.png 1024w\" sizes=\"(max-width: 2121px) 100vw, 2121px\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71247ca2 elementor-nav-menu__align-center elementor-hidden-tablet elementor-hidden-mobile elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"71247ca2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-71247ca2\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-6895\"><a href=\"https:\/\/startbigger.com\/home\/\" class=\"elementor-item\">\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7495\"><a href=\"https:\/\/startbigger.com\/home\/home-page\/about-us\/\" class=\"elementor-item\">\u0645\u0646 \u0646\u062d\u0646<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-privacy-policy menu-item-6782\"><a rel=\"privacy-policy\" href=\"https:\/\/startbigger.com\/home\/home-page\/privacy-policy\/\" class=\"elementor-item\">\u0633\u064a\u0627\u0633\u0629 \u0627\u0644\u062e\u0635\u0648\u0635\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7481\"><a href=\"https:\/\/startbigger.com\/home\/home-page\/terms-of-service\/\" class=\"elementor-item\">\u0634\u0631\u0648\u0637 \u0648\u0623\u062d\u0643\u0627\u0645 \u0627\u0644\u062e\u062f\u0645\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-6899\"><a href=\"https:\/\/sis.startbigger.com\/index.php?rp=\/login\" class=\"elementor-item\">\u062a\u0633\u062c\u064a\u0644 \u0627\u0644\u062f\u062e\u0648\u0644<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-6900\"><a href=\"https:\/\/sis.startbigger.com\/register.php?language=arabic\" class=\"elementor-item\">\u0627\u0644\u062a\u0633\u062c\u064a\u0644<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-71247ca2\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-6895\"><a href=\"https:\/\/startbigger.com\/home\/\" class=\"elementor-item\" tabindex=\"-1\">\u0627\u0644\u0635\u0641\u062d\u0629 \u0627\u0644\u0631\u0626\u064a\u0633\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7495\"><a href=\"https:\/\/startbigger.com\/home\/home-page\/about-us\/\" class=\"elementor-item\" tabindex=\"-1\">\u0645\u0646 \u0646\u062d\u0646<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-privacy-policy menu-item-6782\"><a rel=\"privacy-policy\" href=\"https:\/\/startbigger.com\/home\/home-page\/privacy-policy\/\" class=\"elementor-item\" tabindex=\"-1\">\u0633\u064a\u0627\u0633\u0629 \u0627\u0644\u062e\u0635\u0648\u0635\u064a\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7481\"><a href=\"https:\/\/startbigger.com\/home\/home-page\/terms-of-service\/\" class=\"elementor-item\" tabindex=\"-1\">\u0634\u0631\u0648\u0637 \u0648\u0623\u062d\u0643\u0627\u0645 \u0627\u0644\u062e\u062f\u0645\u0629<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-6899\"><a href=\"https:\/\/sis.startbigger.com\/index.php?rp=\/login\" class=\"elementor-item\" tabindex=\"-1\">\u062a\u0633\u062c\u064a\u0644 \u0627\u0644\u062f\u062e\u0648\u0644<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-6900\"><a href=\"https:\/\/sis.startbigger.com\/register.php?language=arabic\" class=\"elementor-item\" tabindex=\"-1\">\u0627\u0644\u062a\u0633\u062c\u064a\u0644<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0627\u062e\u062a\u0631 \u0627\u0644\u064a\u0648\u0645 \u062b\u0645 \u0627\u0644\u0633\u0627\u0639\u0629 \u0627\u0644\u0645\u0646\u0627\u0633\u0628\u0629 \u0644\u0643 \u0644\u062d\u062c\u0632 \u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0645\u0639 \u062e\u0628\u0631\u0627\u0626\u0646\u0627 *\u064a\u0631\u062c\u0649 \u0627\u0636\u0627\u0641\u0629 \u0631\u0642\u0645 \u0647\u0627\u062a\u0641 \u064a\u0645\u062a\u0644\u0643 \u0627\u0644\u0648\u0627\u062a\u0633 \u0627\u0628 * \u062d\u062a\u0649 \u062a\u0635\u0644\u0643 \u0631\u0633\u0627\u0644\u0629 \u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u0645\u0648\u0639\u062f \u0627\u0644\u062e\u0637\u0648\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0628\u062f\u0627\u064a\u0629 \u0643\u0628\u064a\u0631\u0629<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":6696,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-6937","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/pages\/6937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/comments?post=6937"}],"version-history":[{"count":46,"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/pages\/6937\/revisions"}],"predecessor-version":[{"id":7449,"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/pages\/6937\/revisions\/7449"}],"up":[{"embeddable":true,"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/pages\/6696"}],"wp:attachment":[{"href":"https:\/\/startbigger.com\/home\/wp-json\/wp\/v2\/media?parent=6937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}